{"id":26,"date":"2021-10-07T05:16:12","date_gmt":"2021-10-07T05:16:12","guid":{"rendered":"https:\/\/wordpress.iqonic.design\/product\/wp-free\/allora\/?page_id=26"},"modified":"2021-10-08T13:05:16","modified_gmt":"2021-10-08T13:05:16","slug":"portfolio","status":"publish","type":"page","link":"https:\/\/wordpress.iqonic.design\/product\/wp-free\/allora\/portfolio\/","title":{"rendered":"Portfolio"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"26\" class=\"elementor elementor-26\">\n\t\t\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-f5b896c elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"f5b896c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-07405dc\" data-id=\"07405dc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-section elementor-inner-section elementor-element elementor-element-2c68897 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2c68897\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-97af257\" data-id=\"97af257\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-30c6e12 elementor-widget elementor-widget-qi_addons_for_elementor_image_gallery_masonry\" data-id=\"30c6e12\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"qi_addons_for_elementor_image_gallery_masonry.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-image-gallery-masonry qodef-qi-fslightbox-popup qodef-popup-gallery qodef-image--hover-zoom qodef-qi-grid qodef-layout--qi-masonry qodef-items--fixed qodef-col-num--4 qodef-responsive--custom qodef-col-num--1680--3 qodef-col-num--1440--3 qodef-col-num--1366--3 qodef-col-num--1024--3 qodef-col-num--768--2 qodef-col-num--680--1 qodef-col-num--480--1\">\n\t<div class=\"qodef-grid-inner\">\n\t\t\t<div class=\"qodef-qi-grid-masonry-sizer\"><\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item qodef-item--square\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/wordpress.iqonic.design\/product\/wp-free\/allora\/wp-content\/uploads\/2021\/10\/1-4.jpg\" data-type=\"image\" data-fslightbox=\"gallery-1\">\n\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/wordpress.iqonic.design\/product\/wp-free\/allora\/wp-content\/uploads\/2021\/10\/1-4-650x650.jpg\" class=\"attachment-qi_addons_for_elementor_image_size_square size-qi_addons_for_elementor_image_size_square\" alt=\"g11\" srcset=\"https:\/\/wordpress.iqonic.design\/product\/wp-free\/allora\/wp-content\/uploads\/2021\/10\/1-4-650x650.jpg 650w, https:\/\/wordpress.iqonic.design\/product\/wp-free\/allora\/wp-content\/uploads\/2021\/10\/1-4-150x150.jpg 150w\" sizes=\"(min-width: 960px) 75vw, 100vw\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item qodef-item--square\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/wordpress.iqonic.design\/product\/wp-free\/allora\/wp-content\/uploads\/2021\/10\/nojan-namdar-EDvo0uRBcE8-unsplash-1.jpg\" data-type=\"image\" data-fslightbox=\"gallery-1\">\n\t\t\t\t\t<img decoding=\"async\" width=\"301\" height=\"266\" src=\"https:\/\/wordpress.iqonic.design\/product\/wp-free\/allora\/wp-content\/uploads\/2021\/10\/nojan-namdar-EDvo0uRBcE8-unsplash-1.jpg\" class=\"attachment-qi_addons_for_elementor_image_size_square size-qi_addons_for_elementor_image_size_square\" alt=\"g110\" sizes=\"(min-width: 960px) 75vw, 100vw\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item qodef-item--portrait\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/wordpress.iqonic.design\/product\/wp-free\/allora\/wp-content\/uploads\/2021\/10\/7-2.jpg\" data-type=\"image\" data-fslightbox=\"gallery-1\">\n\t\t\t\t\t<img decoding=\"async\" width=\"650\" height=\"696\" src=\"https:\/\/wordpress.iqonic.design\/product\/wp-free\/allora\/wp-content\/uploads\/2021\/10\/7-2-650x696.jpg\" class=\"attachment-qi_addons_for_elementor_image_size_portrait size-qi_addons_for_elementor_image_size_portrait\" alt=\"g17\" sizes=\"(min-width: 960px) 75vw, 100vw\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item qodef-item--square\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/wordpress.iqonic.design\/product\/wp-free\/allora\/wp-content\/uploads\/2021\/10\/8-2.jpg\" data-type=\"image\" data-fslightbox=\"gallery-1\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/wordpress.iqonic.design\/product\/wp-free\/allora\/wp-content\/uploads\/2021\/10\/8-2-650x650.jpg\" class=\"attachment-qi_addons_for_elementor_image_size_square size-qi_addons_for_elementor_image_size_square\" alt=\"g18\" srcset=\"https:\/\/wordpress.iqonic.design\/product\/wp-free\/allora\/wp-content\/uploads\/2021\/10\/8-2-650x650.jpg 650w, https:\/\/wordpress.iqonic.design\/product\/wp-free\/allora\/wp-content\/uploads\/2021\/10\/8-2-150x150.jpg 150w\" sizes=\"(min-width: 960px) 75vw, 100vw\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item qodef-item--huge-square\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/wordpress.iqonic.design\/product\/wp-free\/allora\/wp-content\/uploads\/2021\/10\/2-4.jpg\" data-type=\"image\" data-fslightbox=\"gallery-1\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"824\" height=\"696\" src=\"https:\/\/wordpress.iqonic.design\/product\/wp-free\/allora\/wp-content\/uploads\/2021\/10\/2-4.jpg\" class=\"attachment-qi_addons_for_elementor_image_size_huge-square size-qi_addons_for_elementor_image_size_huge-square\" alt=\"g12\" srcset=\"https:\/\/wordpress.iqonic.design\/product\/wp-free\/allora\/wp-content\/uploads\/2021\/10\/2-4.jpg 824w, https:\/\/wordpress.iqonic.design\/product\/wp-free\/allora\/wp-content\/uploads\/2021\/10\/2-4-300x253.jpg 300w, https:\/\/wordpress.iqonic.design\/product\/wp-free\/allora\/wp-content\/uploads\/2021\/10\/2-4-768x649.jpg 768w\" sizes=\"(min-width: 960px) 75vw, 100vw\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item qodef-item--\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/wordpress.iqonic.design\/product\/wp-free\/allora\/wp-content\/uploads\/2021\/10\/5-2.jpg\" data-type=\"image\" data-fslightbox=\"gallery-1\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"824\" height=\"696\" src=\"https:\/\/wordpress.iqonic.design\/product\/wp-free\/allora\/wp-content\/uploads\/2021\/10\/5-2.jpg\" class=\"attachment- size-\" alt=\"g15\" srcset=\"https:\/\/wordpress.iqonic.design\/product\/wp-free\/allora\/wp-content\/uploads\/2021\/10\/5-2.jpg 824w, https:\/\/wordpress.iqonic.design\/product\/wp-free\/allora\/wp-content\/uploads\/2021\/10\/5-2-300x253.jpg 300w, https:\/\/wordpress.iqonic.design\/product\/wp-free\/allora\/wp-content\/uploads\/2021\/10\/5-2-768x649.jpg 768w\" sizes=\"(min-width: 960px) 75vw, 100vw\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item qodef-item--square\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/wordpress.iqonic.design\/product\/wp-free\/allora\/wp-content\/uploads\/2021\/10\/3-3.jpg\" data-type=\"image\" data-fslightbox=\"gallery-1\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/wordpress.iqonic.design\/product\/wp-free\/allora\/wp-content\/uploads\/2021\/10\/3-3-650x650.jpg\" class=\"attachment-qi_addons_for_elementor_image_size_square size-qi_addons_for_elementor_image_size_square\" alt=\"g13\" srcset=\"https:\/\/wordpress.iqonic.design\/product\/wp-free\/allora\/wp-content\/uploads\/2021\/10\/3-3-650x650.jpg 650w, https:\/\/wordpress.iqonic.design\/product\/wp-free\/allora\/wp-content\/uploads\/2021\/10\/3-3-150x150.jpg 150w\" sizes=\"(min-width: 960px) 75vw, 100vw\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item qodef-item--\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/wordpress.iqonic.design\/product\/wp-free\/allora\/wp-content\/uploads\/2021\/10\/6-2.jpg\" data-type=\"image\" data-fslightbox=\"gallery-1\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"824\" height=\"696\" src=\"https:\/\/wordpress.iqonic.design\/product\/wp-free\/allora\/wp-content\/uploads\/2021\/10\/6-2.jpg\" class=\"attachment- size-\" alt=\"g16\" srcset=\"https:\/\/wordpress.iqonic.design\/product\/wp-free\/allora\/wp-content\/uploads\/2021\/10\/6-2.jpg 824w, https:\/\/wordpress.iqonic.design\/product\/wp-free\/allora\/wp-content\/uploads\/2021\/10\/6-2-300x253.jpg 300w, https:\/\/wordpress.iqonic.design\/product\/wp-free\/allora\/wp-content\/uploads\/2021\/10\/6-2-768x649.jpg 768w\" sizes=\"(min-width: 960px) 75vw, 100vw\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-26","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/wordpress.iqonic.design\/product\/wp-free\/allora\/wp-json\/wp\/v2\/pages\/26","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wordpress.iqonic.design\/product\/wp-free\/allora\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/wordpress.iqonic.design\/product\/wp-free\/allora\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/wordpress.iqonic.design\/product\/wp-free\/allora\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wordpress.iqonic.design\/product\/wp-free\/allora\/wp-json\/wp\/v2\/comments?post=26"}],"version-history":[{"count":0,"href":"https:\/\/wordpress.iqonic.design\/product\/wp-free\/allora\/wp-json\/wp\/v2\/pages\/26\/revisions"}],"wp:attachment":[{"href":"https:\/\/wordpress.iqonic.design\/product\/wp-free\/allora\/wp-json\/wp\/v2\/media?parent=26"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}